{"id":2434,"date":"2023-08-12T12:54:00","date_gmt":"2023-08-12T17:54:00","guid":{"rendered":"https:\/\/cnlearning.apc.org\/resources\/the-last-mile-internet-connectivity-solutions-guide-sustainable-connectivity-options-for-unconnected-sites\/"},"modified":"2023-08-29T13:45:42","modified_gmt":"2023-08-29T18:45:42","slug":"guia-de-soluciones-de-conectividad-a-internet-de-ultima-milla-opciones-de-conectividad-sostenible-para-emplazamientos-no-conectados","status":"publish","type":"resources","link":"https:\/\/cnlearning.apc.org\/es\/recursos\/guia-de-soluciones-de-conectividad-a-internet-de-ultima-milla-opciones-de-conectividad-sostenible-para-emplazamientos-no-conectados\/","title":{"rendered":"Gu\u00eda de soluciones de conectividad a Internet de \u00faltima milla: Opciones de conectividad sostenible para lugares sin conexi\u00f3n"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Casi la mitad de la poblaci\u00f3n mundial carec\u00eda de acceso a Internet en 2019, y la mayor\u00eda de estas personas viven en las zonas rurales y remotas de las econom\u00edas en desarrollo. Reducir la brecha digital es un imperativo social y econ\u00f3mico teniendo en cuenta que la salud, la educaci\u00f3n, el gobierno y otros servicios y aplicaciones dependen de una conectividad asequible, fiable y de alta velocidad para servir a las comunidades de todo el mundo. La Gu\u00eda de soluciones de conectividad de \u00faltima milla de la UIT est\u00e1 concebida para apoyar a los gobiernos en su funci\u00f3n de regulaci\u00f3n, financiaci\u00f3n y aplicaci\u00f3n del acceso universal a la conectividad. Esta gu\u00eda ofrece formas de identificar las zonas no conectadas y de seleccionar soluciones t\u00e9cnicas, financieras y reglamentarias sostenibles para garantizar la asequibilidad y la accesibilidad a los servicios de conectividad pertinentes.<\/p>","protected":false},"featured_media":2467,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"category_tag":[],"class_list":["post-2434","resources","type-resources","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/cnlearning.apc.org\/es\/wp-json\/wp\/v2\/resources\/2434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnlearning.apc.org\/es\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/cnlearning.apc.org\/es\/wp-json\/wp\/v2\/types\/resources"}],"version-history":[{"count":1,"href":"https:\/\/cnlearning.apc.org\/es\/wp-json\/wp\/v2\/resources\/2434\/revisions"}],"predecessor-version":[{"id":2466,"href":"https:\/\/cnlearning.apc.org\/es\/wp-json\/wp\/v2\/resources\/2434\/revisions\/2466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnlearning.apc.org\/es\/wp-json\/wp\/v2\/media\/2467"}],"wp:attachment":[{"href":"https:\/\/cnlearning.apc.org\/es\/wp-json\/wp\/v2\/media?parent=2434"}],"wp:term":[{"taxonomy":"category_tag","embeddable":true,"href":"https:\/\/cnlearning.apc.org\/es\/wp-json\/wp\/v2\/category_tag?post=2434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}