{"id":2381,"date":"2023-08-13T22:52:20","date_gmt":"2023-08-14T03:52:20","guid":{"rendered":"https:\/\/cnlearning.apc.org\/resources\/our-role-in-the-ict-sector\/"},"modified":"2023-08-14T22:54:29","modified_gmt":"2023-08-15T03:54:29","slug":"nosso-papel-no-setor-de-tic","status":"publish","type":"resources","link":"https:\/\/cnlearning.apc.org\/pt\/recursos\/nosso-papel-no-setor-de-tic\/","title":{"rendered":"Nosso papel no setor de TIC"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>O governo da Nova Zel\u00e2ndia supervisiona v\u00e1rias legisla\u00e7\u00f5es importantes relacionadas a telecomunica\u00e7\u00f5es, incluindo a Lei de Telecomunica\u00e7\u00f5es de 2001 para promover a concorr\u00eancia, a Lei de Telecomunica\u00e7\u00f5es (Capacidade de Intercepta\u00e7\u00e3o e Seguran\u00e7a) de 2013 para capacidade de intercepta\u00e7\u00e3o e seguran\u00e7a, e outras como a Lei de Radiocomunica\u00e7\u00f5es de 1989, a Lei de Servi\u00e7os Postais de 1998 e outras. Eles gerenciam registros, aplicam regulamenta\u00e7\u00f5es, fornecem consultoria sobre pol\u00edticas, monitoram as fun\u00e7\u00f5es de telecomunica\u00e7\u00f5es e representam o pa\u00eds em f\u00f3runs internacionais de TIC. Tamb\u00e9m coordenam o desenvolvimento de pol\u00edticas de com\u00e9rcio eletr\u00f4nico para garantir que as transa\u00e7\u00f5es eletr\u00f4nicas sejam facilitadas sem barreiras legais. A InternetNZ colabora com o gerenciamento do nome de dom\u00ednio .nz.<\/p>","protected":false},"featured_media":2375,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"category_tag":[],"class_list":["post-2381","resources","type-resources","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/resources\/2381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/types\/resources"}],"version-history":[{"count":1,"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/resources\/2381\/revisions"}],"predecessor-version":[{"id":2385,"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/resources\/2381\/revisions\/2385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/media\/2375"}],"wp:attachment":[{"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/media?parent=2381"}],"wp:term":[{"taxonomy":"category_tag","embeddable":true,"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/category_tag?post=2381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}