{"id":2811,"date":"2023-11-08T09:10:59","date_gmt":"2023-11-08T14:10:59","guid":{"rendered":"https:\/\/cnlearning.apc.org\/resources\/situating-network-infrastructure-with-people-practices-and-beyond-a-community\/"},"modified":"2023-11-08T09:41:46","modified_gmt":"2023-11-08T14:41:46","slug":"situar-a-infraestrutura-de-rede-com-as-praticas-das-pessoas-e-alem-de-uma-comunidade","status":"publish","type":"resources","link":"https:\/\/cnlearning.apc.org\/pt\/recursos\/situar-a-infraestrutura-de-rede-com-as-praticas-das-pessoas-e-alem-de-uma-comunidade\/","title":{"rendered":"Situando a infraestrutura de rede com pessoas, pr\u00e1ticas e al\u00e9m: Uma comunidade"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Este workshop re\u00fane pesquisadores multidisciplinares e implementadores que trabalham com desenvolvimento de infraestrutura e conectividade. Ele aborda desafios e oportunidades na interse\u00e7\u00e3o da infraestrutura de rede e da intera\u00e7\u00e3o humano-computador. Ele explora a influ\u00eancia de fatores sociais e pol\u00edticos na constru\u00e7\u00e3o da rede e destaca a import\u00e2ncia de perspectivas alternativas no projeto da rede. O workshop busca promover a colabora\u00e7\u00e3o e compartilhar recursos para repensar as infraestruturas de rede a partir de abordagens centradas no ser humano, na comunidade e na sociedade.<\/p>","protected":false},"featured_media":2669,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"category_tag":[],"class_list":["post-2811","resources","type-resources","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/resources\/2811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/types\/resources"}],"version-history":[{"count":2,"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/resources\/2811\/revisions"}],"predecessor-version":[{"id":2846,"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/resources\/2811\/revisions\/2846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/media\/2669"}],"wp:attachment":[{"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/media?parent=2811"}],"wp:term":[{"taxonomy":"category_tag","embeddable":true,"href":"https:\/\/cnlearning.apc.org\/pt\/wp-json\/wp\/v2\/category_tag?post=2811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}